{"id":6740,"date":"2025-10-24T09:58:56","date_gmt":"2025-10-24T07:58:56","guid":{"rendered":"https:\/\/idemdental.es\/politique-de-cookies\/"},"modified":"2026-06-02T15:49:23","modified_gmt":"2026-06-02T13:49:23","slug":"politique-de-cookies","status":"publish","type":"page","link":"https:\/\/idemdental.es\/fr\/politique-de-cookies\/","title":{"rendered":"Politique de cookies"},"content":{"rendered":"<style>.elementor-6740 .elementor-element.elementor-element-9392dea{--display:flex;--min-height:50vh;--flex-direction:column;--container-widget-width:100%;--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;--justify-content:flex-end;--overlay-opacity:0.8;}.elementor-6740 .elementor-element.elementor-element-9392dea:not(.elementor-motion-effects-element-type-background), .elementor-6740 .elementor-element.elementor-element-9392dea > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:transparent;background-image:linear-gradient(180deg, var( --e-global-color-1736420 ) 0%, var( --e-global-color-1694098 ) 100%);}.elementor-6740 .elementor-element.elementor-element-9392dea::before, .elementor-6740 .elementor-element.elementor-element-9392dea > .elementor-background-video-container::before, .elementor-6740 .elementor-element.elementor-element-9392dea > .e-con-inner > .elementor-background-video-container::before, .elementor-6740 .elementor-element.elementor-element-9392dea > .elementor-background-slideshow::before, .elementor-6740 .elementor-element.elementor-element-9392dea > .e-con-inner > .elementor-background-slideshow::before, .elementor-6740 .elementor-element.elementor-element-9392dea > .elementor-motion-effects-container > .elementor-motion-effects-layer::before{--background-overlay:'';background-color:var( --e-global-color-primary );}.elementor-widget-heading .elementor-heading-title{font-family:var( --e-global-typography-primary-font-family ), Sans-serif;font-weight:var( --e-global-typography-primary-font-weight );text-decoration:var( --e-global-typography-primary-text-decoration );color:var( --e-global-color-primary );}.elementor-6740 .elementor-element.elementor-element-1412847 .elementor-heading-title{font-family:\"Roboto\", Sans-serif;font-size:64px;font-weight:300;text-decoration:none;color:#FFFFFF;}.elementor-6740 .elementor-element.elementor-element-cea69f3{--display:flex;}.elementor-widget-text-editor{font-family:var( --e-global-typography-text-font-family ), Sans-serif;font-weight:var( --e-global-typography-text-font-weight );text-decoration:var( --e-global-typography-text-text-decoration );color:var( --e-global-color-text );}.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:var( --e-global-color-primary );}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap, .elementor-widget-text-editor.elementor-drop-cap-view-default .elementor-drop-cap{color:var( --e-global-color-primary );border-color:var( --e-global-color-primary );}.elementor-6740 .elementor-element.elementor-element-84b7b27{--display:flex;}:root{--page-title-display:none;}@media(max-width:767px){.elementor-6740 .elementor-element.elementor-element-9392dea{--min-height:45vh;--justify-content:flex-end;}.elementor-6740 .elementor-element.elementor-element-1412847 .elementor-heading-title{font-size:42px;}.elementor-6740 .elementor-element.elementor-element-1412847{padding:4% 4% 4% 4%;}.elementor-6740 .elementor-element.elementor-element-cea69f3{--padding-top:4%;--padding-bottom:4%;--padding-left:4%;--padding-right:4%;}}<\/style>\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6740\" class=\"elementor elementor-6740 elementor-5288\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9392dea e-flex e-con-boxed e-con e-parent\" data-id=\"9392dea\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1412847 elementor-widget elementor-widget-heading\" data-id=\"1412847\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Politique de cookies<\/h1>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cea69f3 e-flex e-con-boxed e-con e-parent\" data-id=\"cea69f3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4347cf4 elementor-widget elementor-widget-text-editor\" data-id=\"4347cf4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Chez Idem Dental, nous nous engageons \u00e0 prot\u00e9ger la vie priv\u00e9e de nos utilisateurs et \u00e0 faire preuve de transparence dans le traitement de leurs donn\u00e9es personnelles. La pr\u00e9sente Politique de cookies explique ce que sont les cookies, comment nous les utilisons sur le site web <a href=\"https:\/\/www.idemdental.es?utm_source=chatgpt.com\">www.idemdental.es<\/a> et comment vous pouvez les g\u00e9rer, conform\u00e9ment au R\u00e8glement (UE) 2016\/679 (RGPD), \u00e0 la Loi 34\/2002 sur les services de la soci\u00e9t\u00e9 de l\u2019information et le commerce \u00e9lectronique (LSSI-CE) et aux directives applicables de Google Consent Mode v2. <\/p>\n<h2><ol><li><strong> Qu\u2019est-ce que les cookies ?<\/strong><\/li><\/ol><\/h2>\n<p>Les cookies sont de petits fichiers texte qu\u2019un site web stocke dans le navigateur ou sur l\u2019appareil de l\u2019utilisateur lorsqu\u2019il visite une page web. Leur objectif est de permettre le bon fonctionnement du site, de m\u00e9moriser les pr\u00e9f\u00e9rences de navigation et de recueillir des informations statistiques ou comportementales afin d\u2019am\u00e9liorer l\u2019exp\u00e9rience utilisateur. <\/p>\n<p>Les cookies peuvent \u00eatre :<\/p>\n<ul>\n<li><strong>Cookies internes :<\/strong> g\u00e9r\u00e9s directement par le propri\u00e9taire du site web.<\/li>\n<li><strong>Cookies tiers :<\/strong> g\u00e9r\u00e9s par des entit\u00e9s externes qui fournissent des services au propri\u00e9taire du site web.<\/li>\n<\/ul>\n<div>&nbsp;<\/div>\n<h2><ol start=\"2\"><li><strong> Types de cookies utilis\u00e9s sur ce site web<\/strong><\/li><\/ol><\/h2>\n<p>Sur ce site web, nous utilisons les cat\u00e9gories de cookies suivantes :<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a80536 elementor-widget elementor-widget-html\" data-id=\"9a80536\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<div class=\"cky-audit-table-element\"><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-84b7b27 e-flex e-con-boxed e-con e-parent\" data-id=\"84b7b27\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1505b21 elementor-widget elementor-widget-text-editor\" data-id=\"1505b21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2>\n<ol start=\"3\">\n<li><strong> Gestion du consentement et Google Consent Mode v2<\/strong><\/li>\n<\/ol>\n<\/h2>\n<p>Idem Dental utilise une plateforme de gestion du consentement (CMP) fournie par CookieYes pour g\u00e9rer les pr\u00e9f\u00e9rences de cookies des utilisateurs.<\/p>\n<p>Cet outil permet de respecter les obligations \u00e9tablies par le RGPD, la LSSI-CE et les directives de Google Consent Mode v2.<\/p>\n<p>Google Consent Mode v2 est une technologie qui communique aux services Google l\u2019\u00e9tat du consentement de l\u2019utilisateur concernant l\u2019utilisation de cookies analytiques et publicitaires. Gr\u00e2ce \u00e0 cela, des outils tels que Google Analytics ou Google Ads adaptent leur fonctionnement en fonction des pr\u00e9f\u00e9rences s\u00e9lectionn\u00e9es par l\u2019utilisateur. <\/p>\n<p>Idem Dental garantit que :<\/p>\n<ul>\n<li>Le consentement est demand\u00e9 au pr\u00e9alable, de mani\u00e8re claire et explicite, avant l\u2019installation de cookies non n\u00e9cessaires.<\/li>\n<li>L\u2019utilisateur peut accepter, refuser ou configurer ses pr\u00e9f\u00e9rences facilement.<\/li>\n<li>Les pr\u00e9f\u00e9rences s\u00e9lectionn\u00e9es sont respect\u00e9es et correctement transmises aux services Google.<\/li>\n<li>Le consentement peut \u00eatre modifi\u00e9 ou retir\u00e9 \u00e0 tout moment depuis le panneau de configuration des cookies disponible sur le site web.<\/li>\n<\/ul>\n<p>* Pour en savoir plus sur la mani\u00e8re dont Google utilise vos donn\u00e9es personnelles lorsque vous donnez votre consentement sur notre site web, vous pouvez consulter le _<a href=\"https:\/\/business.safety.google\/privacy\/\"><em>Site de responsabilit\u00e9 des donn\u00e9es commerciales de Google<\/em><\/a>.<\/p>\n<h2>\n<ol start=\"4\">\n<li><strong> Comment g\u00e9rer ou d\u00e9sactiver les cookies<\/strong><\/li>\n<\/ol>\n<\/h2>\n<p>L\u2019utilisateur peut g\u00e9rer ses pr\u00e9f\u00e9rences de cookies \u00e0 tout moment via le panneau de configuration disponible sur le site web.<\/p>\n<p>De plus, la plupart des navigateurs permettent de bloquer, de restreindre ou de supprimer les cookies via les param\u00e8tres du navigateur utilis\u00e9.<\/p>\n<p>Vous pouvez consulter les informations sp\u00e9cifiques \u00e0 chaque navigateur via les liens suivants :<\/p>\n<ul>\n<li>Google Chrome : <a href=\"https:\/\/support.google.com\/chrome\/answer\/95647?hl=es\">cliquez ici<\/a><\/li>\n<li>Mozilla Firefox : <a href=\"http:\/\/support.mozilla.org\/es\/kb\/habilitar-y-deshabilitar-cookies-que-los-sitios-we\">cliquez ici<\/a><\/li>\n<li>Internet Explorer : <a href=\"http:\/\/support.microsoft.com\/kb\/196955\">cliquez ici<\/a><\/li>\n<li>Safari : <a href=\"http:\/\/support.apple.com\/kb\/HT1677?viewlocale=es_ES\">cliquez ici<\/a><\/li>\n<li>Opera : <a href=\"http:\/\/help.opera.com\/Windows\/11.50\/es-ES\/cookies.html\">cliquez ici<\/a><\/li>\n<\/ul><div><br><\/div>\n<p>La d\u00e9sactivation de certains cookies peut affecter le bon fonctionnement du site web.<\/p>\n<h2>\n<ol start=\"5\">\n<li><strong> Transferts internationaux de donn\u00e9es<\/strong><\/li>\n<\/ol>\n<\/h2>\n<p>Certains services tiers utilis\u00e9s sur ce site web, tels que Google Analytics ou Google reCAPTCHA, peuvent impliquer des transferts internationaux de donn\u00e9es en dehors de l\u2019Espace \u00e9conomique europ\u00e9en.<\/p>\n<p>Ces transferts sont effectu\u00e9s en appliquant les garanties appropri\u00e9es conform\u00e9ment \u00e0 la r\u00e9glementation europ\u00e9enne sur la protection des donn\u00e9es.<\/p>\n<h2>\n<ol start=\"6\">\n<li><strong> Mises \u00e0 jour de la Politique de cookies<\/strong><\/li>\n<\/ol>\n<\/h2>\n<p>Idem Dental se r\u00e9serve le droit de modifier la pr\u00e9sente Politique de cookies afin de l\u2019adapter aux changements l\u00e9gislatifs, techniques ou au fonctionnement du site web.<\/p>\n<p>Il est recommand\u00e9 \u00e0 l\u2019utilisateur de consulter r\u00e9guli\u00e8rement cette politique afin de rester inform\u00e9 de l\u2019utilisation des cookies.<\/p>\n<h2>\n<ol start=\"7\">\n<li><strong> Contact<\/strong><\/li>\n<\/ol>\n<\/h2>\n<p>Pour toute question relative \u00e0 la pr\u00e9sente Politique de cookies, vous pouvez contacter Idem Dental via les canaux de contact habituels disponibles sur le site web :<\/p>\n<p><a href=\"https:\/\/www.idemdental.es?utm_source=chatgpt.com\">www.idemdental.es<\/a><\/p>\n<h2>&nbsp;<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Politique de cookies Chez Idem Dental, nous nous engageons \u00e0 prot\u00e9ger la vie priv\u00e9e de nos utilisateurs et \u00e0 faire preuve de transparence dans le traitement de leurs donn\u00e9es personnelles. La pr\u00e9sente Politique de cookies explique ce que sont les cookies, comment nous les utilisons sur le site web www.idemdental.es et comment vous pouvez les [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-6740","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Politique de cookies - IDEM<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Politique de cookies - IDEM\" \/>\n<meta property=\"og:description\" content=\"Politique de cookies Chez Idem Dental, nous nous engageons \u00e0 prot\u00e9ger la vie priv\u00e9e de nos utilisateurs et \u00e0 faire preuve de transparence dans le traitement de leurs donn\u00e9es personnelles. La pr\u00e9sente Politique de cookies explique ce que sont les cookies, comment nous les utilisons sur le site web www.idemdental.es et comment vous pouvez les [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/idemdental.es\/fr\/politique-de-cookies\/\" \/>\n<meta property=\"og:site_name\" content=\"IDEM\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-02T13:49:23+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/idemdental.es\/fr\/politique-de-cookies\/\",\"url\":\"https:\/\/idemdental.es\/fr\/politique-de-cookies\/\",\"name\":\"Politique de cookies - IDEM\",\"isPartOf\":{\"@id\":\"https:\/\/idemdental.es\/fr\/#website\"},\"datePublished\":\"2025-10-24T07:58:56+00:00\",\"dateModified\":\"2026-06-02T13:49:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/idemdental.es\/fr\/politique-de-cookies\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/idemdental.es\/fr\/politique-de-cookies\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/idemdental.es\/fr\/politique-de-cookies\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/idemdental.es\/fr\/accueil\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Politique de cookies\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/idemdental.es\/fr\/#website\",\"url\":\"https:\/\/idemdental.es\/fr\/\",\"name\":\"IDEM\",\"description\":\"Cl\u00ednica dental Alicante\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/idemdental.es\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Politique de cookies - IDEM","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Politique de cookies - IDEM","og_description":"Politique de cookies Chez Idem Dental, nous nous engageons \u00e0 prot\u00e9ger la vie priv\u00e9e de nos utilisateurs et \u00e0 faire preuve de transparence dans le traitement de leurs donn\u00e9es personnelles. La pr\u00e9sente Politique de cookies explique ce que sont les cookies, comment nous les utilisons sur le site web www.idemdental.es et comment vous pouvez les [&hellip;]","og_url":"https:\/\/idemdental.es\/fr\/politique-de-cookies\/","og_site_name":"IDEM","article_modified_time":"2026-06-02T13:49:23+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/idemdental.es\/fr\/politique-de-cookies\/","url":"https:\/\/idemdental.es\/fr\/politique-de-cookies\/","name":"Politique de cookies - IDEM","isPartOf":{"@id":"https:\/\/idemdental.es\/fr\/#website"},"datePublished":"2025-10-24T07:58:56+00:00","dateModified":"2026-06-02T13:49:23+00:00","breadcrumb":{"@id":"https:\/\/idemdental.es\/fr\/politique-de-cookies\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/idemdental.es\/fr\/politique-de-cookies\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/idemdental.es\/fr\/politique-de-cookies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/idemdental.es\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"Politique de cookies"}]},{"@type":"WebSite","@id":"https:\/\/idemdental.es\/fr\/#website","url":"https:\/\/idemdental.es\/fr\/","name":"IDEM","description":"Cl\u00ednica dental Alicante","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/idemdental.es\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/idemdental.es\/fr\/wp-json\/wp\/v2\/pages\/6740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/idemdental.es\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/idemdental.es\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/idemdental.es\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/idemdental.es\/fr\/wp-json\/wp\/v2\/comments?post=6740"}],"version-history":[{"count":3,"href":"https:\/\/idemdental.es\/fr\/wp-json\/wp\/v2\/pages\/6740\/revisions"}],"predecessor-version":[{"id":7283,"href":"https:\/\/idemdental.es\/fr\/wp-json\/wp\/v2\/pages\/6740\/revisions\/7283"}],"wp:attachment":[{"href":"https:\/\/idemdental.es\/fr\/wp-json\/wp\/v2\/media?parent=6740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}